{"id":4268,"date":"2026-07-05T22:04:15","date_gmt":"2026-07-05T20:04:15","guid":{"rendered":"https:\/\/germaniahorstmar.de\/leichtathletik\/?p=4268"},"modified":"2026-07-05T22:09:09","modified_gmt":"2026-07-05T20:09:09","slug":"horstmarer-leichtathleten-auf-nationaler-buehne","status":"publish","type":"post","link":"https:\/\/germaniahorstmar.de\/leichtathletik\/20260705-horstmarer-leichtathleten-auf-nationaler-buehne\/","title":{"rendered":"Horstmarer Leichtathleten auf nationaler B\u00fchne"},"content":{"rendered":"\n<p class=\"isSelectedEnd\"><span style=\"font-size: revert\">Mit der Teilnahme an den Deutschen Jugendmeisterschaften der U18 und U23 im Lohrheidestadion in Bochum-Wattenscheid haben Eva Deitmaring, Jenna Haudek und Max Wolgast einen weiteren H\u00f6hepunkt ihrer Leichtathletik-Karriere erlebt. Die drei Horstmarer starteten im Trikot der LG Brillux M\u00fcnster und pr\u00e4sentierten sich auf nationaler B\u00fchne mit starken Leistungen.<\/span><\/p>\n<p class=\"isSelectedEnd\">Bereits am Freitag waren alle drei in den 4&#215;100-Meter-Staffeln im Einsatz. Eva Deitmaring ging f\u00fcr die weibliche U18 an den Start. Da die schnellste Sprinterin der Mannschaft aufgrund ihres Einzelstarts auf einen Staffeleinsatz verzichtete, war bereits vor dem Rennen klar, dass die starke Qualifikationszeit kaum zu erreichen sein w\u00fcrde. Entsprechend lief das Quartett rund eine Sekunde langsamer als in der Qualifikation ins Ziel, zeigte aber eine geschlossene Mannschaftsleistung und sammelte wertvolle Erfahrungen auf h\u00f6chstem nationalen Niveau.<\/p>\n<p class=\"isSelectedEnd\">\u201eEs ist einfach so cool, bei einer DM zu laufen. Das Gef\u00fchl ist einfach unbeschreiblich und gibt einem die Motivation, immer weiter zu trainieren\u201c, fasste Eva Deitmaring ihre Eindr\u00fccke zusammen.<\/p>\n<p class=\"isSelectedEnd\">F\u00fcr einen Leistungssprung sorgte die Staffel der m\u00e4nnlichen U18 mit Max Wolgast als Startl\u00e4ufer. Das Quartett steigerte seine pers\u00f6nliche Bestzeit von 43,91 auf 43,40 Sekunden und belegte damit den 11. Platz unter 20 Mannschaften.<\/p>\n<p class=\"isSelectedEnd\">Noch erfolgreicher verlief der Wettkampf f\u00fcr Jenna Haudek in der weiblichen U23. Gemeinsam mit ihren Staffelkolleginnen lief sie in 46,74 Sekunden eine neue pers\u00f6nliche Bestleistung. Der f\u00fcnfte Platz unter 18 Staffeln bedeutete zugleich die Bestplatzierung der drei Horstmarer Athleten. Dar\u00fcber hinaus best\u00e4tigte das Quartett mit dieser Zeit die B-Norm f\u00fcr die Deutschen Meisterschaften der Frauen und M\u00e4nner.<\/p>\n<p class=\"isSelectedEnd\">Am Sonntag war Max Wolgast zudem im Stabhochsprung der U18 gefordert. Wechselnde Windverh\u00e4ltnisse erschwerten den Springern den Wettkampf. Der Horstmarer zeigte sich davon zun\u00e4chst unbeeindruckt und \u00fcberquerte alle H\u00f6hen von 4,10 bis 4,45 Metern jeweils im ersten Versuch. Erst an seiner Bestleistung von 4,60 Metern war Endstation. Nach drei Fehlversuchen blieb es bei 4,45 Metern, die ihm einen guten 11. Platz einbrachten \u2013 dieselbe Platzierung, die er bereits mit der Staffel erreicht hatte.<\/p>\n<p>F\u00fcr das Horstmarer Trio war der Auftritt bei den nationalen Titelk\u00e4mpfen nicht nur ein sportlicher Erfolg, sondern auch eine wertvolle Erfahrung, die Motivation f\u00fcr die kommenden Aufgaben geben d\u00fcrfte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit der Teilnahme an den Deutschen Jugendmeisterschaften der U18 und U23 im Lohrheidestadion in Bochum-Wattenscheid haben Eva Deitmaring, Jenna Haudek und Max Wolgast einen weiteren H\u00f6hepunkt ihrer Leichtathletik-Karriere erlebt. Die drei Horstmarer starteten im Trikot der LG Brillux M\u00fcnster und pr\u00e4sentierten sich auf nationaler B\u00fchne mit starken Leistungen. Bereits am<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":27,"featured_media":4269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"class_list":["post-4268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutsche-meisterschaft"],"_links":{"self":[{"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/posts\/4268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/comments?post=4268"}],"version-history":[{"count":1,"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/posts\/4268\/revisions"}],"predecessor-version":[{"id":4270,"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/posts\/4268\/revisions\/4270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/media\/4269"}],"wp:attachment":[{"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/media?parent=4268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/categories?post=4268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/germaniahorstmar.de\/leichtathletik\/wp-json\/wp\/v2\/tags?post=4268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}